{"id":3673,"date":"2013-05-31T12:06:54","date_gmt":"2013-05-31T10:06:54","guid":{"rendered":"https:\/\/doctorfernandopifarre.com\/servicios-de-podologia\/"},"modified":"2026-06-17T22:22:39","modified_gmt":"2026-06-17T20:22:39","slug":"servicios-de-podologia","status":"publish","type":"page","link":"https:\/\/doctorfernandopifarre.com\/es\/servicios-de-podologia\/","title":{"rendered":"Servicios de Podologia"},"content":{"rendered":"<div class=\"wpb-content-wrapper\" id=\"wpb-content-root\"><p>[vc_row css_animation=\u00bb\u00bb row_type=\u00bbrow\u00bb use_row_as_full_screen_section=\u00bbno\u00bb type=\u00bbfull_width\u00bb angled_section=\u00bbno\u00bb text_align=\u00bbleft\u00bb background_image_as_pattern=\u00bbwithout_pattern\u00bb section=\u00bbyes\u00bb background=\u00bbprimary\u00bb parallax_bg_width=\u00bb110&#8243;][vc_column][vc_column_text css=\u00bb\u00bb]<\/p>\n<h1 style=\"text-align: center;\">Servicios de Podolog\u00eda y Podolog\u00eda Deportiva en Lleida<\/h1>\n<p>[\/vc_column_text][vc_empty_space][vc_column_text css=\u00bb\u00bb]<\/p>\n<p style=\"text-align: center;\" data-path-to-node=\"26\">\u00bfSufres dolor en los pies, las rodillas o la espalda al caminar o hacer deporte? En la <strong>cl\u00ednica podol\u00f3gica del Dr. Fernando Pifarr\u00e9 en Lleida<\/strong> ofrecemos una asistencia m\u00e9dica integral. Combinamos la experiencia en <strong>podolog\u00eda cl\u00ednica y medicina del deporte<\/strong> con tecnolog\u00eda de vanguardia para encontrar el origen de tu dolencia y dise\u00f1ar el tratamiento exacto que tu cuerpo necesita.<\/p>\n<div class=\"code-block ng-tns-c1352101635-142 ng-animate-disabled ng-trigger ng-trigger-codeBlockRevealAnimation\" data-hveid=\"0\" data-ved=\"0CAAQhtANahgKEwj9oaKVtY6VAxUAAAAAHQAAAAAQsQM\">\n<div class=\"formatted-code-block-internal-container ng-tns-c1352101635-142\">\n<div class=\"animated-opacity ng-tns-c1352101635-142\">\n<div class=\"code-block-decoration header-formatted gds-emphasized-body-m ng-tns-c1352101635-142 ng-star-inserted\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_empty_space][\/vc_column][\/vc_row][vc_row css_animation=\u00bb\u00bb row_type=\u00bbrow\u00bb use_row_as_full_screen_section=\u00bbno\u00bb type=\u00bbfull_width\u00bb angled_section=\u00bbno\u00bb text_align=\u00bbleft\u00bb background_image_as_pattern=\u00bbwithout_pattern\u00bb parallax_bg_width=\u00bb110&#8243;][vc_column width=\u00bb1\/4&#8243; animate=\u00bbafc\u00bb][vc_single_image image=\u00bb3572&#8243; img_size=\u00bbmedium\u00bb qode_css_animation=\u00bb\u00bb align=\u00bbcenter\u00bb img_link_large=\u00bbyes\u00bb][vc_column_text]La consulta de podologia.[\/vc_column_text][\/vc_column][vc_column width=\u00bb3\/4&#8243;][vc_column_text]<\/p>\n<h2 style=\"text-align: left;\">Quiropodias<\/h2>\n<p>[\/vc_column_text][vc_column_text]<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Es el tratamiento incruento de los callos, ojos de piojo y de las u\u00f1as del pie. Estas lesiones se deben b\u00e1sicamente a una combinaci\u00f3n de dos factores: las deformidades propias de los dedos que <\/span><span style=\"color: #000000;\">al lado de<\/span><span style=\"color: #000000;\"> un exceso de presi\u00f3n del calzado hace que la piel del pie aumente su capa c\u00f3rnea. Mediante las t\u00e9cnicas de <\/span><span class=\"hiddenSpellError\" style=\"color: #000000;\">quirop\u00f2dia<\/span><span style=\"color: #000000;\"> tenim una millora immediata per\u00f2 temporal de les <\/span><span style=\"color: #000000;\">mol\u00e8sties<\/span><span style=\"color: #000000;\">.<\/span><\/p>\n<p>[\/vc_column_text][vc_column_text]<strong><span style=\"color: #000000;\">Tamb\u00e9 podem incloure dins la <\/span><span class=\"hiddenSpellError\" style=\"color: #000000;\">quirop\u00f2dia<\/span><span style=\"color: #000000;\"> el tractament de les:<\/span><\/strong><br style=\"color: #000000;\" \/><br style=\"color: #000000;\" \/><\/p>\n<ul>\n<li>Verrugas plantares.<\/li>\n<li>U\u00f1as <span class=\"hiddenSpellError\">encarnadas<\/span>.<\/li>\n<li>Deformidades de las u\u00f1as.<\/li>\n<li>Infecciones por hongos de la piel del pie o de las u\u00f1as.<\/li>\n<li>Trastornos de la sudoraci\u00f3n del pie.<\/li>\n<li>Traumatismos unguiales agudos o cr\u00f3nicos.<\/li>\n<\/ul>\n<p>[\/vc_column_text][vc_empty_space height=\u00bb50px\u00bb][\/vc_column][\/vc_row][vc_row css_animation=\u00bb\u00bb row_type=\u00bbrow\u00bb use_row_as_full_screen_section=\u00bbno\u00bb type=\u00bbfull_width\u00bb angled_section=\u00bbno\u00bb text_align=\u00bbleft\u00bb background_image_as_pattern=\u00bbwithout_pattern\u00bb section=\u00bbyes\u00bb background=\u00bbalternate\u00bb][vc_column width=\u00bb1\/4&#8243; animate=\u00bbafc\u00bb][vc_single_image image=\u00bb3554&#8243; img_size=\u00bbmedium\u00bb qode_css_animation=\u00bb\u00bb align=\u00bbcenter\u00bb img_link_large=\u00bbyes\u00bb][vc_single_image image=\u00bb3553&#8243; img_size=\u00bbmedium\u00bb qode_css_animation=\u00bb\u00bb align=\u00bbcenter\u00bb img_link_large=\u00bbyes\u00bb][vc_column_text]Aparatos para el estudio del pie.[\/vc_column_text][\/vc_column][vc_column width=\u00bb3\/4&#8243;][vc_column_text]<\/p>\n<h2 style=\"text-align: left;\">Exploraci\u00f3n Biomec\u00e1nica<\/h2>\n<p>[\/vc_column_text][vc_column_text]<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Consisteix <\/span><span style=\"color: #000000;\">a<\/span><span style=\"color: #000000;\">fer una <strong>exploraci\u00f3 <\/strong><\/span><strong><span style=\"color: #000000;\">completa<\/span><\/strong><span style=\"color: #000000;\"><strong> de les articulacions, musculatura, tendons, lligaments<\/strong>&#8230; de les extremitats inferiors a fi de poder obtenir un diagn\u00f2stic de perqu\u00e8 li fa mal el peu o altres articulacions del cos.<\/span><br style=\"color: #000000;\" \/><br style=\"color: #000000;\" \/><span style=\"color: #000000;\">Para realizar esta exploraci\u00f3n utilizamos desde los m\u00e9todos tradicionales de exploraci\u00f3n como de los m\u00e9todos inform\u00e1ticos m\u00e1s modernos.<\/span><br style=\"color: #000000;\" \/><br style=\"color: #000000;\" \/><strong><span style=\"color: #000000;\">Nosaltres disposem d\u2019un banc de marxa de 4 metres que t\u00e9 incorporat 3 c\u00e0meres de <\/span> <span style=\"color: #000000;\">v\u00eddeo<\/span><\/strong><span style=\"color: #000000;\">per a realitzar l\u2019estudi est\u00e0tic i din\u00e0mic de les pressions plantars com l\u2019estudi de la marxa humana. <strong>Tamb\u00e9 disposem <\/strong><\/span><strong><span style=\"color: #000000;\">d&#8217;un<\/span> <span style=\"color: #000000;\"> tap\u00eds mec\u00e0nic per estudiar el gest esportiu.<\/span><\/strong><br style=\"color: #000000;\" \/><br style=\"color: #000000;\" \/><span style=\"color: #000000;\">Cuando un paciente tiene dolor en el pie o en otro lugar es muy probable que precise tratamiento con plantillas para controlar los momentos pronadores y\/o<\/span><span style=\"color: #000000;\">supinadores<\/span><\/p>\n<p>[\/vc_column_text][vc_empty_space height=\u00bb50px\u00bb][\/vc_column][\/vc_row][vc_row css_animation=\u00bb\u00bb row_type=\u00bbrow\u00bb use_row_as_full_screen_section=\u00bbno\u00bb type=\u00bbfull_width\u00bb angled_section=\u00bbno\u00bb text_align=\u00bbleft\u00bb background_image_as_pattern=\u00bbwithout_pattern\u00bb section=\u00bbyes\u00bb][vc_column width=\u00bb1\/4&#8243; animate=\u00bbafc\u00bb][vc_single_image image=\u00bb3555&#8243; img_size=\u00bbmedium\u00bb qode_css_animation=\u00bb\u00bb align=\u00bbcenter\u00bb img_link_large=\u00bbyes\u00bb][vc_column_text]Taller ortop\u00e9dico.[\/vc_column_text][\/vc_column][vc_column width=\u00bb3\/4&#8243;][vc_column_text]<\/p>\n<h2 style=\"text-align: left;\">Ortopodologia<\/h2>\n<p>[\/vc_column_text][vc_column_text]<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Es la parte de la podolog\u00eda que se encarga de realizar las pr\u00f3tesis y ortesis plantares. Estas <\/span><span class=\"hiddenSpellError\" style=\"color: #000000;\">pr\u00f2tesis<\/span><span style=\"color: #000000;\"> plantars poden ser plantilles ortop\u00e8diques, <\/span><span class=\"hiddenSpellError\" style=\"color: #000000;\">pr\u00f2tesis<\/span><span style=\"color: #000000;\"> de silicones, f\u00e8rules per als peus&#8230;<\/span><br style=\"color: #000000;\" \/><br style=\"color: #000000;\" \/><strong><span style=\"color: #000000;\">Nosotros hacemos tres tipos de plantillas ortop\u00e9dicas:<\/span><\/strong><br style=\"color: #000000;\" \/><br style=\"color: #000000;\" \/><\/p>\n<ol>\n<li style=\"text-align: justify;\"><strong>Por elementos: <\/strong><span style=\"color: #333333;\">damunt d\u2019una <span class=\"hiddenSpellError\">palmilla<\/span> tallada a mida apliquem diferents <span class=\"hiddenSpellError\">cunyes<\/span> en funci\u00f3 de la patologia que h<span class=\"hiddenGrammarError\">em<\/span> diagnosticat pr\u00e8viament a l\u2019exploraci\u00f3 biomec\u00e0nica. Despu\u00e9s la forramos de piel y la cosemos. Son un tipo de plantillas muy apreciadas por las se\u00f1oras, ya que son muy peque\u00f1as y poco gruesas por lo que pueden llevarse pr\u00e1cticamente en cualquier tipo de calzado<\/span><span style=\"color: #333333;\">.<\/span><\/li>\n<li style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>De termopl\u00e0stics:<\/strong> previamente hay que realizar un molde de yeso del pie. \u00c9ste puede hacerse de pie o <\/span><span style=\"color: #000000;\">tumbado<\/span><span style=\"color: #000000;\"> en la litera. Nosotros utilizamos como termopl\u00e1stico el s<\/span><span class=\"hiddenSpellError\" style=\"color: #000000;\">ubortholen<\/span><span style=\"color: #000000;\"> i p<\/span><span class=\"hiddenGreenError\" style=\"color: #000000;\">olipropil\u00e9<\/span><span style=\"color: #000000;\"> de 2 mm., 3 mm.i 4 mm. Estos materiales <\/span><span style=\"color: #000000;\">son<\/span> <span class=\"hiddenSpellError\" style=\"color: #000000;\">termoadaptable<\/span><span style=\"color: #000000;\"> a <\/span><span class=\"hiddenGrammarError\" style=\"color: #000000;\">180\u00ba<\/span><span style=\"color: #000000;\"> de temperatura. Son las m\u00e1s utilizables en podolog\u00eda pedi\u00e1trica. Estas plantillas pueden lavarse con agua.<\/span><\/li>\n<li style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>De resines:<\/strong> son uno del tipo de plantillas m\u00e1s modernas del mercado. Consiste <\/span><span style=\"color: #000000;\">a<\/span><span style=\"color: #000000;\"> combinar un parell de resines <\/span><span class=\"hiddenSpellError\" style=\"color: #000000;\">termoadaptables<\/span><span style=\"color: #000000;\"> de <\/span><span style=\"color: #000000;\">diferent<\/span><span style=\"color: #000000;\"> dureza. Por encima ponemos <\/span><span class=\"hiddenGrammarError\" style=\"color: #000000;\">un Eva<\/span><span style=\"color: #000000;\"> de diferentes densidades. Tambi\u00e9n se pueden combinar otros tipos de material. Es necesario hacer molde de yeso. Por su capacidad de<\/span><span class=\"hiddenSpellError\" style=\"color: #000000;\">amortiguaci\u00f3<\/span><span style=\"color: #000000;\"> s\u00f3n les m\u00e9s utilitzades per esportistes, pacients diab\u00e8tics&#8230;<\/span><\/li>\n<\/ol>\n<p>[\/vc_column_text][vc_empty_space height=\u00bb50px\u00bb][\/vc_column][\/vc_row][vc_row css_animation=\u00bb\u00bb row_type=\u00bbrow\u00bb use_row_as_full_screen_section=\u00bbno\u00bb type=\u00bbfull_width\u00bb angled_section=\u00bbno\u00bb text_align=\u00bbleft\u00bb background_image_as_pattern=\u00bbwithout_pattern\u00bb section=\u00bbyes\u00bb background=\u00bbalternate\u00bb parallax_bg_width=\u00bb110&#8243;][vc_column width=\u00bb1\/4&#8243; animate=\u00bbafc\u00bb][vc_single_image image=\u00bb3773&#8243; img_size=\u00bbmedium\u00bb onclick=\u00bbimg_link_large\u00bb qode_css_animation=\u00bb\u00bb align=\u00bbcenter\u00bb][vc_single_image image=\u00bb3771&#8243; img_size=\u00bbmedium\u00bb onclick=\u00bbimg_link_large\u00bb qode_css_animation=\u00bb\u00bb align=\u00bbcenter\u00bb][vc_column_text]El quir\u00f3fano de la consulta de cirug\u00eda.[\/vc_column_text][\/vc_column][vc_column width=\u00bb3\/4&#8243;][vc_column_text]<\/p>\n<h2 style=\"text-align: left;\">Cirugia podol\u00f3gica<\/h2>\n<p>[\/vc_column_text][vc_column_text]<\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"color: #000000;\">Muchas patolog\u00edas del pie pueden tener soluci\u00f3n definitiva con la cirug\u00eda podol\u00f3gica<\/span><span style=\"color: #000000;\">.<\/span><\/strong><br style=\"color: #000000;\" \/><br style=\"color: #000000;\" \/><span style=\"color: #000000;\">Nosotros utilizamos la cirurgia <\/span><span class=\"hiddenSpellError\" style=\"color: #000000;\">percutanea<\/span><span style=\"color: #000000;\"> o de m\u00ednima incisi\u00f3n. Son un conjunto de t\u00e9cnicas quir\u00fargicas que se empezaron a realizar en USA y que ya hace bastante tiempo se introdujeron en el nuestro <\/span><span style=\"color: #000000;\">pa\u00eds<\/span><span style=\"color: #000000;\">. Tienen como denominador com\u00fan que: son ambulatorias, se realizan con anestesia local, con incisiones s\u00f3lo de 2-4 mm. y se caracterizan por un postoperatorio pr\u00e1cticamente indoloro.<\/span><br style=\"color: #000000;\" \/><br style=\"color: #000000;\" \/><span style=\"color: #000000;\">Entre las patolog\u00edas que son susceptibles de mejorar con cirug\u00eda <\/span><span class=\"hiddenSpellError\" style=\"color: #000000;\">percutania<\/span><span style=\"color: #000000;\"> tenemos: dedos en garra, juanetes, ojos de piojo, espol\u00f3n calc\u00e1neo..<\/span><\/p>\n<p>[\/vc_column_text][vc_accordion style=\u00bbaccordion\u00bb toggle=\u00bbyes\u00bb][vc_accordion_tab title=\u00bbCaso 1&#8243;][vc_row_inner row_type=\u00bbrow\u00bb type=\u00bbfull_width\u00bb text_align=\u00bbleft\u00bb css_animation=\u00bb\u00bb][vc_column_inner width=\u00bb1\/3&#8243;][vc_single_image image=\u00bb3583&#8243; img_size=\u00bbmedium\u00bb qode_css_animation=\u00bb\u00bb animate=\u00bbafc\u00bb align=\u00bbcenter\u00bb img_link_large=\u00bbyes\u00bb][vc_column_text]Imagen real pre-operatoria.[\/vc_column_text][vc_single_image image=\u00bb3585&#8243; img_size=\u00bbmedium\u00bb qode_css_animation=\u00bb\u00bb animate=\u00bbafc\u00bb align=\u00bbcenter\u00bb img_link_large=\u00bbyes\u00bb][vc_column_text]Cirug\u00eda percut\u00e1nea o de m\u00ednima incisi\u00f3n.[\/vc_column_text][\/vc_column_inner][vc_column_inner width=\u00bb1\/3&#8243;][vc_single_image image=\u00bb3556&#8243; img_size=\u00bbmedium\u00bb qode_css_animation=\u00bb\u00bb animate=\u00bbafc\u00bb align=\u00bbcenter\u00bb img_link_large=\u00bbyes\u00bb][vc_column_text]<span id=\"sbswc6vn9w4l_4\" class=\"sbswc6vn9w4l\">Radiografia<\/span> pre-operat\u00f2ria.[\/vc_column_text][vc_single_image image=\u00bb3557&#8243; img_size=\u00bbmedium\u00bb qode_css_animation=\u00bb\u00bb animate=\u00bbafc\u00bb align=\u00bbcenter\u00bb img_link_large=\u00bbyes\u00bb][vc_column_text]Ventaja post operatoria.[\/vc_column_text][\/vc_column_inner][vc_column_inner width=\u00bb1\/3&#8243;][vc_single_image image=\u00bb3584&#8243; img_size=\u00bbmedium\u00bb qode_css_animation=\u00bb\u00bb animate=\u00bbafc\u00bb align=\u00bbcenter\u00bb img_link_large=\u00bbyes\u00bb][vc_column_text]Anestesia <span id=\"sbswc6vn9w4l_6\" class=\"sbswc6vn9w4l\">local.<\/span>[\/vc_column_text][vc_single_image image=\u00bb3587&#8243; img_size=\u00bbmedium\u00bb qode_css_animation=\u00bb\u00bb animate=\u00bbafc\u00bb align=\u00bbcenter\u00bb img_link_large=\u00bbyes\u00bb][vc_column_text]Radiografia post-operatoria.[\/vc_column_text][vc_single_image image=\u00bb3591&#8243; img_size=\u00bbmedium\u00bb qode_css_animation=\u00bb\u00bb animate=\u00bbafc\u00bb align=\u00bbcenter\u00bb img_link_large=\u00bbyes\u00bb][vc_column_text]Resultado final.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_accordion_tab][vc_accordion_tab title=\u00bbCaso 2&#8243;][vc_row_inner row_type=\u00bbrow\u00bb type=\u00bbfull_width\u00bb text_align=\u00bbleft\u00bb css_animation=\u00bb\u00bb][vc_column_inner width=\u00bb1\/3&#8243;][vc_single_image image=\u00bb3588&#8243; img_size=\u00bbmedium\u00bb qode_css_animation=\u00bb\u00bb animate=\u00bbafc\u00bb align=\u00bbcenter\u00bb img_link_large=\u00bbyes\u00bb][vc_column_text]<\/p>\n<p class=\"center\">Imagen real pre-operatoria.<\/p>\n<p>[\/vc_column_text][vc_separator type=\u00bbnormal\u00bb][\/vc_column_inner][vc_column_inner width=\u00bb1\/3&#8243;][vc_single_image image=\u00bb3589&#8243; img_size=\u00bbmedium\u00bb qode_css_animation=\u00bb\u00bb animate=\u00bbafc\u00bb align=\u00bbcenter\u00bb img_link_large=\u00bbyes\u00bb][vc_column_text]Radiografia pre-operatoria.[\/vc_column_text][vc_separator type=\u00bbnormal\u00bb][\/vc_column_inner][vc_column_inner width=\u00bb1\/3&#8243;][vc_single_image image=\u00bb3590&#8243; img_size=\u00bbmedium\u00bb qode_css_animation=\u00bb\u00bb animate=\u00bbafc\u00bb align=\u00bbcenter\u00bb img_link_large=\u00bbyes\u00bb][vc_column_text]Imagen real post-operatoria.[\/vc_column_text][vc_separator type=\u00bbnormal\u00bb][\/vc_column_inner][\/vc_row_inner][\/vc_accordion_tab][\/vc_accordion][vc_empty_space height=\u00bb50px\u00bb][\/vc_column][\/vc_row][vc_row css_animation=\u00bb\u00bb row_type=\u00bbrow\u00bb use_row_as_full_screen_section=\u00bbno\u00bb type=\u00bbfull_width\u00bb angled_section=\u00bbno\u00bb text_align=\u00bbleft\u00bb background_image_as_pattern=\u00bbwithout_pattern\u00bb section=\u00bbyes\u00bb][vc_column width=\u00bb1\/4&#8243;][vc_single_image image=\u00bb3561&#8243; img_size=\u00bbmedium\u00bb qode_css_animation=\u00bb\u00bb animate=\u00bbafc\u00bb align=\u00bbcenter\u00bb img_link_large=\u00bbyes\u00bb][vc_column_text][\/vc_column_text][\/vc_column][vc_column width=\u00bb3\/4&#8243;][vc_column_text]<\/p>\n<h2 style=\"text-align: left;\">Radiologia digital<\/h2>\n<p>[\/vc_column_text][vc_column_text]<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">La consulta de Podologia del Dr. <\/span><span class=\"hiddenSpellError\" style=\"color: #000000;\">Fernando<\/span> <span class=\"hiddenSpellError\" style=\"color: #000000;\">Pifarr\u00e9<\/span><span style=\"color: #000000;\"> disposa d\u2019aparell de Raigs X Digital <\/span><span class=\"hiddenSpellError\" style=\"color: #000000;\">Satelec<\/span><span style=\"color: #000000;\"> de tensi\u00f3 m\u00e0xima de 70 <\/span><span style=\"color: #000000;\">KV<\/span><span style=\"color: #000000;\"> y de intensidad m\u00e1xima de 8 mA. El revelat es <\/span><span style=\"color: #000000;\">a los pocos segundos<\/span><span style=\"color: #000000;\"> y al ser digital no genera ning\u00fan tipo de residuo.<\/span><br style=\"color: #000000;\" \/><br style=\"color: #000000;\" \/><strong><span style=\"color: #000000;\">Tamb\u00e9 disposa de <\/span><span style=\"color: #000000;\">fluoroscopi<\/span><span style=\"color: #000000;\"> per la <\/span><span style=\"color: #000000;\">cirurgia<\/span> <span style=\"color: #000000;\">percut\u00e0nia<\/span><span style=\"color: #000000;\">.<\/span><\/strong><br style=\"color: #000000;\" \/><br style=\"color: #000000;\" \/><span style=\"color: #000000;\">Para la seguridad de los pacientes y del personal, la consulta dispone para el control de las radiaciones de<\/span><span style=\"color: #000000;\">dosimetro<\/span><span style=\"color: #000000;\"> de area.<\/span><br style=\"color: #000000;\" \/><br style=\"color: #000000;\" \/><br style=\"color: #000000;\" \/><\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row css_animation=\u00bb\u00bb row_type=\u00bbrow\u00bb use_row_as_full_screen_section=\u00bbno\u00bb type=\u00bbfull_width\u00bb angled_section=\u00bbno\u00bb text_align=\u00bbleft\u00bb background_image_as_pattern=\u00bbwithout_pattern\u00bb][vc_column][vc_empty_space height=\u00bb72px\u00bb][vc_column_text css=\u00bb\u00bb]<\/p>\n<h2 style=\"text-align: center;\">Pide Cita en nuestra Cl\u00ednica de Podolog\u00eda en Lleida<\/h2>\n<p>&nbsp;<\/p>\n<ul>\n<li><b>La salud empieza por tus pies. No dejes que una peque\u00f1a molestia se convierta en una lesi\u00f3n cr\u00f3nica.<\/b><\/li>\n<li style=\"text-align: center;\"><b>Direcci\u00f3n de la consulta:<\/b> Av. Prat de la Riba 42, 2\u00ba 1\u00aa, 25004 Lleida<\/li>\n<li style=\"text-align: center;\"><b>Tel\u00e9fono de contacto:<\/b> <a class=\"ng-star-inserted\" href=\"https:\/\/www.google.com\/search?q=tel:973238433\" target=\"_blank\" rel=\"noopener\" data-hveid=\"0\" data-ved=\"0CAAQ_4QMahgKEwj9oaKVtY6VAxUAAAAAHQAAAAAQswM\">973 23 84 33<\/a><\/li>\n<li>\n<p style=\"text-align: center;\"><b>Atenci\u00f3n personalizada<\/b> por el Dr. Fernando Pifarr\u00e9.<\/p>\n<\/li>\n<\/ul>\n<p>[\/vc_column_text][vc_empty_space height=\u00bb72px\u00bb][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row css_animation=\u00bb\u00bb row_type=\u00bbrow\u00bb use_row_as_full_screen_section=\u00bbno\u00bb type=\u00bbfull_width\u00bb angled_section=\u00bbno\u00bb text_align=\u00bbleft\u00bb background_image_as_pattern=\u00bbwithout_pattern\u00bb section=\u00bbyes\u00bb background=\u00bbprimary\u00bb parallax_bg_width=\u00bb110&#8243;][vc_column][vc_column_text css=\u00bb\u00bb] Servicios de Podolog\u00eda y Podolog\u00eda Deportiva en Lleida [\/vc_column_text][vc_empty_space][vc_column_text css=\u00bb\u00bb] \u00bfSufres dolor en los pies, las rodillas o la espalda al caminar o hacer deporte? En la cl\u00ednica podol\u00f3gica del Dr. Fernando Pifarr\u00e9&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-3673","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Servicios de Podologia - Doctor Fernando Pifarr\u00e9<\/title>\n<meta name=\"description\" content=\"Descubre los servicios de podolog\u00eda cl\u00ednica, podolog\u00eda deportiva e infantil del Dr. Fernando Pifarr\u00e9 en Lleida. Estudios de la marcha y taller de plantillas propio.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/doctorfernandopifarre.com\/es\/servicios-de-podologia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Servicios de Podologia - Doctor Fernando Pifarr\u00e9\" \/>\n<meta property=\"og:description\" content=\"Descubre los servicios de podolog\u00eda cl\u00ednica, podolog\u00eda deportiva e infantil del Dr. Fernando Pifarr\u00e9 en Lleida. Estudios de la marcha y taller de plantillas propio.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/doctorfernandopifarre.com\/es\/servicios-de-podologia\/\" \/>\n<meta property=\"og:site_name\" content=\"Doctor Fernando Pifarr\u00e9\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-17T20:22:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/doctorfernandopifarre.com\/wp-content\/uploads\/2023\/02\/doctor-fernando-pifarre-logo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"433\" \/>\n\t<meta property=\"og:image:height\" content=\"101\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@fernandopifarre\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/doctorfernandopifarre.com\\\/es\\\/servicios-de-podologia\\\/\",\"url\":\"https:\\\/\\\/doctorfernandopifarre.com\\\/es\\\/servicios-de-podologia\\\/\",\"name\":\"Servicios de Podologia - Doctor Fernando Pifarr\u00e9\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/doctorfernandopifarre.com\\\/es\\\/#website\"},\"datePublished\":\"2013-05-31T10:06:54+00:00\",\"dateModified\":\"2026-06-17T20:22:39+00:00\",\"description\":\"Descubre los servicios de podolog\u00eda cl\u00ednica, podolog\u00eda deportiva e infantil del Dr. Fernando Pifarr\u00e9 en Lleida. Estudios de la marcha y taller de plantillas propio.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/doctorfernandopifarre.com\\\/es\\\/servicios-de-podologia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/doctorfernandopifarre.com\\\/es\\\/servicios-de-podologia\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/doctorfernandopifarre.com\\\/es\\\/servicios-de-podologia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/doctorfernandopifarre.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Servicios de Podologia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/doctorfernandopifarre.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/doctorfernandopifarre.com\\\/es\\\/\",\"name\":\"Doctor Fernando Pifarr\u00e9\",\"description\":\"Pod\u00f3logo en L\u00e9rida Dr Fernando Pifarre, contamos con un equipo de profesionales de la podolog\u00eda y revisiones deportivas con amplia experiencia.\",\"publisher\":{\"@id\":\"https:\\\/\\\/doctorfernandopifarre.com\\\/es\\\/#\\\/schema\\\/person\\\/cb8a61302a753c52201b00abd0ccc993\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/doctorfernandopifarre.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/doctorfernandopifarre.com\\\/es\\\/#\\\/schema\\\/person\\\/cb8a61302a753c52201b00abd0ccc993\",\"name\":\"fpifarre\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/doctorfernandopifarre.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/favicon.png\",\"url\":\"https:\\\/\\\/doctorfernandopifarre.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/favicon.png\",\"contentUrl\":\"https:\\\/\\\/doctorfernandopifarre.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/favicon.png\",\"width\":366,\"height\":502,\"caption\":\"fpifarre\"},\"logo\":{\"@id\":\"https:\\\/\\\/doctorfernandopifarre.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/favicon.png\"},\"description\":\"Dr. en Medicina i Cirurgia (Facultat medicina UdL) metge especialista via MIR en medicina del'educaci\u00f3 f\u00edsica i l'esport (Hospital Cl\u00ednic. Barcelona). Diplomat Universitari en Podologia (UB. Campus de Bellvitge). T\u00e8cnic ortop\u00e8dic oficial (UB. Hospital Cl\u00ednic Barcelona). Cap del servei Medicina Esportiva. Generalitat Catalunya a Lleida. CAP 11 de Setembre Professor Biomec\u00e0nica. (UdL. Universitat Central de Catalunya)\",\"sameAs\":[\"http:\\\/\\\/doctorfernandopifarre.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Servicios de Podologia - Doctor Fernando Pifarr\u00e9","description":"Descubre los servicios de podolog\u00eda cl\u00ednica, podolog\u00eda deportiva e infantil del Dr. Fernando Pifarr\u00e9 en Lleida. Estudios de la marcha y taller de plantillas propio.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/doctorfernandopifarre.com\/es\/servicios-de-podologia\/","og_locale":"es_ES","og_type":"article","og_title":"Servicios de Podologia - Doctor Fernando Pifarr\u00e9","og_description":"Descubre los servicios de podolog\u00eda cl\u00ednica, podolog\u00eda deportiva e infantil del Dr. Fernando Pifarr\u00e9 en Lleida. Estudios de la marcha y taller de plantillas propio.","og_url":"https:\/\/doctorfernandopifarre.com\/es\/servicios-de-podologia\/","og_site_name":"Doctor Fernando Pifarr\u00e9","article_modified_time":"2026-06-17T20:22:39+00:00","og_image":[{"width":433,"height":101,"url":"https:\/\/doctorfernandopifarre.com\/wp-content\/uploads\/2023\/02\/doctor-fernando-pifarre-logo.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@fernandopifarre","twitter_misc":{"Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/doctorfernandopifarre.com\/es\/servicios-de-podologia\/","url":"https:\/\/doctorfernandopifarre.com\/es\/servicios-de-podologia\/","name":"Servicios de Podologia - Doctor Fernando Pifarr\u00e9","isPartOf":{"@id":"https:\/\/doctorfernandopifarre.com\/es\/#website"},"datePublished":"2013-05-31T10:06:54+00:00","dateModified":"2026-06-17T20:22:39+00:00","description":"Descubre los servicios de podolog\u00eda cl\u00ednica, podolog\u00eda deportiva e infantil del Dr. Fernando Pifarr\u00e9 en Lleida. Estudios de la marcha y taller de plantillas propio.","breadcrumb":{"@id":"https:\/\/doctorfernandopifarre.com\/es\/servicios-de-podologia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/doctorfernandopifarre.com\/es\/servicios-de-podologia\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/doctorfernandopifarre.com\/es\/servicios-de-podologia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/doctorfernandopifarre.com\/es\/"},{"@type":"ListItem","position":2,"name":"Servicios de Podologia"}]},{"@type":"WebSite","@id":"https:\/\/doctorfernandopifarre.com\/es\/#website","url":"https:\/\/doctorfernandopifarre.com\/es\/","name":"Doctor Fernando Pifarr\u00e9","description":"Pod\u00f3logo en L\u00e9rida Dr Fernando Pifarre, contamos con un equipo de profesionales de la podolog\u00eda y revisiones deportivas con amplia experiencia.","publisher":{"@id":"https:\/\/doctorfernandopifarre.com\/es\/#\/schema\/person\/cb8a61302a753c52201b00abd0ccc993"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/doctorfernandopifarre.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/doctorfernandopifarre.com\/es\/#\/schema\/person\/cb8a61302a753c52201b00abd0ccc993","name":"fpifarre","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/doctorfernandopifarre.com\/wp-content\/uploads\/2023\/02\/favicon.png","url":"https:\/\/doctorfernandopifarre.com\/wp-content\/uploads\/2023\/02\/favicon.png","contentUrl":"https:\/\/doctorfernandopifarre.com\/wp-content\/uploads\/2023\/02\/favicon.png","width":366,"height":502,"caption":"fpifarre"},"logo":{"@id":"https:\/\/doctorfernandopifarre.com\/wp-content\/uploads\/2023\/02\/favicon.png"},"description":"Dr. en Medicina i Cirurgia (Facultat medicina UdL) metge especialista via MIR en medicina del'educaci\u00f3 f\u00edsica i l'esport (Hospital Cl\u00ednic. Barcelona). Diplomat Universitari en Podologia (UB. Campus de Bellvitge). T\u00e8cnic ortop\u00e8dic oficial (UB. Hospital Cl\u00ednic Barcelona). Cap del servei Medicina Esportiva. Generalitat Catalunya a Lleida. CAP 11 de Setembre Professor Biomec\u00e0nica. (UdL. Universitat Central de Catalunya)","sameAs":["http:\/\/doctorfernandopifarre.com"]}]}},"_links":{"self":[{"href":"https:\/\/doctorfernandopifarre.com\/es\/wp-json\/wp\/v2\/pages\/3673","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/doctorfernandopifarre.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/doctorfernandopifarre.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/doctorfernandopifarre.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/doctorfernandopifarre.com\/es\/wp-json\/wp\/v2\/comments?post=3673"}],"version-history":[{"count":3,"href":"https:\/\/doctorfernandopifarre.com\/es\/wp-json\/wp\/v2\/pages\/3673\/revisions"}],"predecessor-version":[{"id":6463,"href":"https:\/\/doctorfernandopifarre.com\/es\/wp-json\/wp\/v2\/pages\/3673\/revisions\/6463"}],"wp:attachment":[{"href":"https:\/\/doctorfernandopifarre.com\/es\/wp-json\/wp\/v2\/media?parent=3673"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}